{"id":1570,"date":"2015-06-05T00:35:49","date_gmt":"2015-06-04T22:35:49","guid":{"rendered":"http:\/\/helel.eu\/?page_id=1570"},"modified":"2026-02-04T02:27:51","modified_gmt":"2026-02-04T01:27:51","slug":"i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue","status":"publish","type":"page","link":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/","title":{"rendered":"I livelli del quadro comune europeo di riferimento per le lingue"},"content":{"rendered":"<h2>Livello\u00a0elementare<\/h2>\n<h3>A1<\/h3>\n<p>Riesce a capire e usare espressioni familiari di uso quotidiano e frasi molto semplici finalizzate alla soddisfazione di bisogni di tipo concreto. Sa presentare se stesso\/-a e altri, e sa domandare e rispondere su dati personali quali dove vive, le persone che conosce, le cose che possiede. Riesce a interagire in modo semplice a condizione che gli altri parlino lentamente e chiaramente e che siano disponibili e preparati a collaborare.<\/p>\n<h3>A2<\/h3>\n<p>\u00c8 in grado di capire frasi ed espressioni di uso frequente relative ad ambiti di pi\u00f9 immediata rilevanza (informazioni personali e familiari molto di base, acquisti, geografia locale, lavoro). Sa comunicare in attivit\u00e0 semplici e di routine che richiedano uno scambio di informazioni semplice e diretto su argomenti familiari o comunque abituali. Riesce a descrivere in termini semplici alcuni aspetti del proprio vissuto e del proprio ambiente, e argomenti che si riferiscono a bisogni immediati.<\/p>\n<h3><\/h3>\n<h2>Livello\u00a0intermedio<\/h2>\n<h3>B1<\/h3>\n<p>\u00c8 in grado di capire i principali punti di un chiaro input linguistico di tipo standard su contenuti familiari regolarmente incontrati al lavoro, a scuola, nel tempo libero ecc. Sa cavarsela in molte situazioni durante un viaggio in un paese dove sia parlata la lingua oggetto del suo apprendimento. Sa produrre semplici testi dotati di coesione su argomenti che gli sono familiari o che sono di suo interesse. Sa descrivere esperienze e eventi, sogni e speranze, ambizioni, e esporre brevemente ragioni e spiegazioni per opinioni e progetti.<\/p>\n<h3>B2<\/h3>\n<p>\u00c8 in grado di capire le principali idee di un testo complesso su argomenti di natura sia astratta sia concreta, incluse le discussioni di tipo tecnico nel proprio campo di specializzazione. Interagisce con un sufficiente grado di fluenza e spontaneit\u00e0; l\u2019interazione regolare con i parlanti nativi si sviluppa senza eccessivo sforzo da entrambe le parti. Produce testi chiari e articolati su un\u2019ampia gamma di argomenti e sa esporre la propria opinione su un argomento esplicitando i vantaggi e gli svantaggi delle varie opzioni.<\/p>\n<h3><\/h3>\n<h2>Livello\u00a0avanzato<\/h2>\n<h3>C1<\/h3>\n<p>\u00c8 in grado di capire un\u2019ampia gamma di testi, anche lunghi, fino a saper individuare il significato implicito. Si esprime fluentemente e spontaneamente senza un eccessivo sforzo di ricerca delle parole. Usa la lingua in modo flessibile e adeguato agli scopi sociali, accademici e professionali. Sa produrre testi chiari, ben strutturati, articolati su argomenti complessi, sapendo controllare le strutture discorsive e i meccanismi di coesione.<\/p>\n<h3>C2<\/h3>\n<p>\u00c8 in grado di capire senza sforzo praticamente tutto ci\u00f2 che sente o legge. Sa riassumere informazioni da diverse fonti orali e scritte ricostruendo gli argomenti in un testo coerente. Sa esprimersi spontaneamente, in modo molto fluente e preciso, mettendo in evidenza le fini sfumature di significato anche nelle situazioni di particolare complessit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Livello\u00a0elementare A1 Riesce a capire e usare espressioni familiari di uso quotidiano e frasi molto semplici finalizzate alla soddisfazione di bisogni di tipo concreto. Sa presentare se stesso\/-a e altri, e sa domandare e rispondere su dati personali quali dove vive, le persone che conosce, le cose che possiede. Riesce a interagire in modo semplice [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":588,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[194],"tags":[],"class_list":["post-1570","page","type-page","status-publish","hentry","category-corsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I livelli del quadro comune europeo di riferimento per le lingue<\/title>\n<meta name=\"description\" content=\"I livelli del quadro comune europeo di riferimento per le lingue\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I livelli del quadro comune europeo di riferimento per le lingue\" \/>\n<meta property=\"og:description\" content=\"I livelli del quadro comune europeo di riferimento per le lingue\" \/>\n<meta property=\"og:url\" content=\"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecnologia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T01:27:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\\\/\",\"url\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\\\/\",\"name\":\"I livelli del quadro comune europeo di riferimento per le lingue\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/#website\"},\"datePublished\":\"2015-06-04T22:35:49+00:00\",\"dateModified\":\"2026-02-04T01:27:51+00:00\",\"description\":\"I livelli del quadro comune europeo di riferimento per le lingue\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corsi e lezioni\",\"item\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/corsi-e-lezioni\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"I livelli del quadro comune europeo di riferimento per le lingue\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/#website\",\"url\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/\",\"name\":\"Tecnologia\",\"description\":\"All In One\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/ivmhome.ddnsfree.com:8080\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I livelli del quadro comune europeo di riferimento per le lingue","description":"I livelli del quadro comune europeo di riferimento per le lingue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/","og_locale":"it_IT","og_type":"article","og_title":"I livelli del quadro comune europeo di riferimento per le lingue","og_description":"I livelli del quadro comune europeo di riferimento per le lingue","og_url":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/","og_site_name":"Tecnologia","article_modified_time":"2026-02-04T01:27:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/","url":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/","name":"I livelli del quadro comune europeo di riferimento per le lingue","isPartOf":{"@id":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/#website"},"datePublished":"2015-06-04T22:35:49+00:00","dateModified":"2026-02-04T01:27:51+00:00","description":"I livelli del quadro comune europeo di riferimento per le lingue","breadcrumb":{"@id":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/i-livelli-del-quadro-comune-europeo-di-riferimento-per-le-lingue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Corsi e lezioni","item":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/corsi-e-lezioni\/"},{"@type":"ListItem","position":3,"name":"I livelli del quadro comune europeo di riferimento per le lingue"}]},{"@type":"WebSite","@id":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/#website","url":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/","name":"Tecnologia","description":"All In One","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/pages\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/comments?post=1570"}],"version-history":[{"count":1,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/pages\/1570\/revisions"}],"predecessor-version":[{"id":3293,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/pages\/1570\/revisions\/3293"}],"up":[{"embeddable":true,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/pages\/588"}],"wp:attachment":[{"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/categories?post=1570"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ivmhome.ddnsfree.com:8080\/wordpress\/wp-json\/wp\/v2\/tags?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}